{"id":59,"count":309,"description":"","link":"https:\/\/datingsnob.com\/se\/casual\/","name":"Casual","slug":"casual","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>B\u00e4sta Casual dejtingsajterna - Anv\u00e4ndarrecensioner och betyg<\/title>\n<meta name=\"description\" content=\"Hitta de b\u00e4sta Casual dejtingsajterna enligt recensioner och betyg fr\u00e5n anv\u00e4ndare precis som du.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/datingsnob.com\/se\/casual\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00e4sta Casual dejtingsajterna - Anv\u00e4ndarrecensioner och betyg\" \/>\n<meta property=\"og:description\" content=\"Hitta de b\u00e4sta Casual dejtingsajterna enligt recensioner och betyg fr\u00e5n anv\u00e4ndare precis som du.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/datingsnob.com\/se\/casual\/\" \/>\n<meta property=\"og:site_name\" content=\"DatingSnob Sverige\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/datingsnob.com\/se\/casual\/\",\"url\":\"https:\/\/datingsnob.com\/se\/casual\/\",\"name\":\"B\u00e4sta Casual dejtingsajterna - Anv\u00e4ndarrecensioner och betyg\",\"isPartOf\":{\"@id\":\"https:\/\/datingsnob.com\/se\/#website\"},\"description\":\"Hitta de b\u00e4sta Casual dejtingsajterna enligt recensioner och betyg fr\u00e5n anv\u00e4ndare precis som du.\",\"breadcrumb\":{\"@id\":\"https:\/\/datingsnob.com\/se\/casual\/#breadcrumb\"},\"inLanguage\":\"sv-SE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/datingsnob.com\/se\/casual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/datingsnob.com\/se\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/datingsnob.com\/se\/#website\",\"url\":\"https:\/\/datingsnob.com\/se\/\",\"name\":\"DatingSnob Sverige\",\"description\":\"Anv\u00e4ndarrecensioner av Svenska dejtingtj\u00e4nster\",\"publisher\":{\"@id\":\"https:\/\/datingsnob.com\/se\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/datingsnob.com\/se\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/datingsnob.com\/se\/#organization\",\"name\":\"DatingSnob Sverige\",\"url\":\"https:\/\/datingsnob.com\/se\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/datingsnob.com\/se\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/datingsnob.com\/se\/wp-content\/uploads\/sites\/18\/2024\/07\/DatingSnobMainLogo-1.svg\",\"contentUrl\":\"https:\/\/datingsnob.com\/se\/wp-content\/uploads\/sites\/18\/2024\/07\/DatingSnobMainLogo-1.svg\",\"width\":269,\"height\":50,\"caption\":\"DatingSnob Sverige\"},\"image\":{\"@id\":\"https:\/\/datingsnob.com\/se\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00e4sta Casual dejtingsajterna - Anv\u00e4ndarrecensioner och betyg","description":"Hitta de b\u00e4sta Casual dejtingsajterna enligt recensioner och betyg fr\u00e5n anv\u00e4ndare precis som du.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/datingsnob.com\/se\/casual\/","og_locale":"sv_SE","og_type":"article","og_title":"B\u00e4sta Casual dejtingsajterna - Anv\u00e4ndarrecensioner och betyg","og_description":"Hitta de b\u00e4sta Casual dejtingsajterna enligt recensioner och betyg fr\u00e5n anv\u00e4ndare precis som du.","og_url":"https:\/\/datingsnob.com\/se\/casual\/","og_site_name":"DatingSnob Sverige","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/datingsnob.com\/se\/casual\/","url":"https:\/\/datingsnob.com\/se\/casual\/","name":"B\u00e4sta Casual dejtingsajterna - Anv\u00e4ndarrecensioner och betyg","isPartOf":{"@id":"https:\/\/datingsnob.com\/se\/#website"},"description":"Hitta de b\u00e4sta Casual dejtingsajterna enligt recensioner och betyg fr\u00e5n anv\u00e4ndare precis som du.","breadcrumb":{"@id":"https:\/\/datingsnob.com\/se\/casual\/#breadcrumb"},"inLanguage":"sv-SE"},{"@type":"BreadcrumbList","@id":"https:\/\/datingsnob.com\/se\/casual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/datingsnob.com\/se\/"},{"@type":"ListItem","position":2,"name":"Casual"}]},{"@type":"WebSite","@id":"https:\/\/datingsnob.com\/se\/#website","url":"https:\/\/datingsnob.com\/se\/","name":"DatingSnob Sverige","description":"Anv\u00e4ndarrecensioner av Svenska dejtingtj\u00e4nster","publisher":{"@id":"https:\/\/datingsnob.com\/se\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/datingsnob.com\/se\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/datingsnob.com\/se\/#organization","name":"DatingSnob Sverige","url":"https:\/\/datingsnob.com\/se\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/datingsnob.com\/se\/#\/schema\/logo\/image\/","url":"https:\/\/datingsnob.com\/se\/wp-content\/uploads\/sites\/18\/2024\/07\/DatingSnobMainLogo-1.svg","contentUrl":"https:\/\/datingsnob.com\/se\/wp-content\/uploads\/sites\/18\/2024\/07\/DatingSnobMainLogo-1.svg","width":269,"height":50,"caption":"DatingSnob Sverige"},"image":{"@id":"https:\/\/datingsnob.com\/se\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/datingsnob.com\/se\/wp-json\/wp\/v2\/product_cat\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/datingsnob.com\/se\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/datingsnob.com\/se\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/datingsnob.com\/se\/wp-json\/wp\/v2\/product?product_cat=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}